{"id":305161,"date":"2023-05-30T18:11:33","date_gmt":"2023-05-30T17:11:33","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/bone-6-gomos-adulto-100alg-270grs-m2-2\/"},"modified":"2026-02-06T14:18:02","modified_gmt":"2026-02-06T14:18:02","slug":"duran","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/duran\/","title":{"rendered":"Adult 6-Shirt 100% Alg. 270Grs\/m2"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Bon&eacute; Duran 6 gomos 100% algod&atilde;o, 270grs\/mq.<br \/>Com refor&ccedil;o frontal completo.<\/p>\n<p>&middot;\tbon&eacute; tipo Beisebol com design de dois tons<br \/>&middot;\tconfeccionado em tecido espesso de sarja 100% algod&atilde;o de toque suave que proporciona durabilidade, resist&ecirc;ncia e facilita a transpira&ccedil;&atilde;o<br \/>&middot;\tviseira curva, (com cores combinadas contrastantes que continuam at&eacute; &agrave; coroa traseira), o que impede a entrada dos raios solares e proporciona maior frescura<br \/>&middot;\t&Aacute;rea frontal curva com costura central e refor&ccedil;o interior termo-fixo para reduzir a deforma&ccedil;&atilde;o, e banda interior em redor do contorno para maior conforto<br \/>&middot;\tabertura traseira semicircular com aba de velcro para um melhor ajuste<br \/>&middot;\tm&eacute;todos adequados de marca&ccedil;&atilde;o: bordado, costura, etc<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Bon&eacute; Duran 6 gomos 100% algod&atilde;o, 270grs\/mq.<br \/>Com refor&ccedil;o frontal completo.<\/p>\n<p>&middot;\tbon&eacute; tipo Beisebol com design de dois tons<br \/>&middot;\tconfeccionado em tecido espesso de sarja 100% algod&atilde;o de toque suave que proporciona durabilidade, resist&ecirc;ncia e facilita a transpira&ccedil;&atilde;o<br \/>&middot;\tviseira curva, (com cores combinadas contrastantes que continuam at&eacute; &agrave; coroa traseira), o que impede a entrada dos raios solares e proporciona maior frescura<br \/>&middot;\t&Aacute;rea frontal curva com costura central e refor&ccedil;o interior termo-fixo para reduzir a deforma&ccedil;&atilde;o, e banda interior em redor do contorno para maior conforto<br \/>&middot;\tabertura traseira semicircular com aba de velcro para um melhor ajuste<br \/>&middot;\tm&eacute;todos adequados de marca&ccedil;&atilde;o: bordado, costura, etc<\/p>\n<\/div>","protected":false},"featured_media":395113,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2763],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2 - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/duran\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2 - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Bon&eacute; Duran 6 gomos 100% algod&atilde;o, 270grs\/mq.Com refor&ccedil;o frontal completo.&middot; bon&eacute; tipo Beisebol com design de dois tons&middot; confeccionado em tecido espesso de sarja 100% algod&atilde;o de toque suave que proporciona durabilidade, resist&ecirc;ncia e facilita a transpira&ccedil;&atilde;o&middot; viseira curva, (com cores combinadas contrastantes que continuam at&eacute; &agrave; coroa traseira), o que impede a entrada dos raios solares e proporciona maior frescura&middot; &Aacute;rea frontal curva com costura central e refor&ccedil;o interior termo-fixo para reduzir a deforma&ccedil;&atilde;o, e banda interior em redor do contorno para maior conforto&middot; abertura traseira semicircular com aba de velcro para um melhor ajuste&middot; m&eacute;todos adequados de marca&ccedil;&atilde;o: bordado, costura, etc\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/duran\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T14:18:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"701\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/\",\"name\":\"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2 - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg\",\"datePublished\":\"2023-05-30T17:11:33+00:00\",\"dateModified\":\"2026-02-06T14:18:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg\",\"width\":701,\"height\":701,\"caption\":\"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2 - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/duran\/","og_locale":"en_GB","og_type":"article","og_title":"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2 - NorSafe","og_description":"Bon&eacute; Duran 6 gomos 100% algod&atilde;o, 270grs\/mq.Com refor&ccedil;o frontal completo.&middot; bon&eacute; tipo Beisebol com design de dois tons&middot; confeccionado em tecido espesso de sarja 100% algod&atilde;o de toque suave que proporciona durabilidade, resist&ecirc;ncia e facilita a transpira&ccedil;&atilde;o&middot; viseira curva, (com cores combinadas contrastantes que continuam at&eacute; &agrave; coroa traseira), o que impede a entrada dos raios solares e proporciona maior frescura&middot; &Aacute;rea frontal curva com costura central e refor&ccedil;o interior termo-fixo para reduzir a deforma&ccedil;&atilde;o, e banda interior em redor do contorno para maior conforto&middot; abertura traseira semicircular com aba de velcro para um melhor ajuste&middot; m&eacute;todos adequados de marca&ccedil;&atilde;o: bordado, costura, etc","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/duran\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T14:18:02+00:00","og_image":[{"width":701,"height":701,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/","name":"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2 - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg","datePublished":"2023-05-30T17:11:33+00:00","dateModified":"2026-02-06T14:18:02+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_duran.jpg","width":701,"height":701,"caption":"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/duran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Bon\u00e9 6 Gomos Adulto 100%Alg. 270Grs\/m2"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/305161"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=305161"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/395113"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=305161"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=305161"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=305161"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}