{"id":310629,"date":"2023-05-30T19:33:01","date_gmt":"2023-05-30T18:33:01","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/cinta-lombar\/"},"modified":"2026-02-06T18:13:55","modified_gmt":"2026-02-06T18:13:55","slug":"910-322-3-4-5","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/910-322-3-4-5\/","title":{"rendered":"Lumbar belt without suspenders"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Cinta Lombar<\/p>\n<p>Cinta lombar fabricada em poli&eacute;ster com spandex para exercer a resist&ecirc;ncia adequada.<br \/>Apoio traseiro em PP (polipropileno) com fecho de velcro (de nylon) para maior prote&ccedil;&atilde;o da zona lombar.<br \/>Proporciona suporte na parte inferior das costas e no abd&oacute;men, permitindo liberdade de movimentos e m&aacute;ximo conforto, gra&ccedil;as &agrave; sua forma anat&oacute;mica.<br \/>Sem suspens&oacute;rios.<br \/>Incorpora fecho com velcro assim como tensor de ajuste tamb&eacute;m com velcro.<br \/>Desta forma, oferece maior fixa&ccedil;&atilde;o e mobilidade.<br \/>Lav&aacute;vel e transpir&aacute;vel. Suporte din&acirc;mico e flex&iacute;vel que n&atilde;o impede o movimento. Sem partes mec&acirc;nicas que possam estragar-se ou que tenham que ser combinadas. Incorpora quatro espartilhos.<\/p>\n<p>CE. Fabricada em conformidade com as exig&ecirc;ncias essenciais de sanidade e de seguran&ccedil;a especificadas no Regulamento (UE) 2016\/425<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Cinta Lombar<\/p>\n<p>Cinta lombar fabricada em poli&eacute;ster com spandex para exercer a resist&ecirc;ncia adequada.<br \/>Apoio traseiro em PP (polipropileno) com fecho de velcro (de nylon) para maior prote&ccedil;&atilde;o da zona lombar.<br \/>Proporciona suporte na parte inferior das costas e no abd&oacute;men, permitindo liberdade de movimentos e m&aacute;ximo conforto, gra&ccedil;as &agrave; sua forma anat&oacute;mica.<br \/>Sem suspens&oacute;rios.<br \/>Incorpora fecho com velcro assim como tensor de ajuste tamb&eacute;m com velcro.<br \/>Desta forma, oferece maior fixa&ccedil;&atilde;o e mobilidade.<br \/>Lav&aacute;vel e transpir&aacute;vel. Suporte din&acirc;mico e flex&iacute;vel que n&atilde;o impede o movimento. Sem partes mec&acirc;nicas que possam estragar-se ou que tenham que ser combinadas. Incorpora quatro espartilhos.<\/p>\n<p>CE. Fabricada em conformidade com as exig&ecirc;ncias essenciais de sanidade e de seguran&ccedil;a especificadas no Regulamento (UE) 2016\/425<\/p>\n<\/div>","protected":false},"featured_media":361762,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2735,2734],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cinta Lombar Sem Suspens\u00f3rios - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/910-322-3-4-5\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cinta Lombar Sem Suspens\u00f3rios - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Cinta LombarCinta lombar fabricada em poli&eacute;ster com spandex para exercer a resist&ecirc;ncia adequada.Apoio traseiro em PP (polipropileno) com fecho de velcro (de nylon) para maior prote&ccedil;&atilde;o da zona lombar.Proporciona suporte na parte inferior das costas e no abd&oacute;men, permitindo liberdade de movimentos e m&aacute;ximo conforto, gra&ccedil;as &agrave; sua forma anat&oacute;mica.Sem suspens&oacute;rios.Incorpora fecho com velcro assim como tensor de ajuste tamb&eacute;m com velcro.Desta forma, oferece maior fixa&ccedil;&atilde;o e mobilidade.Lav&aacute;vel e transpir&aacute;vel. Suporte din&acirc;mico e flex&iacute;vel que n&atilde;o impede o movimento. Sem partes mec&acirc;nicas que possam estragar-se ou que tenham que ser combinadas. Incorpora quatro espartilhos.CE. Fabricada em conformidade com as exig&ecirc;ncias essenciais de sanidade e de seguran&ccedil;a especificadas no Regulamento (UE) 2016\/425\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/910-322-3-4-5\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T18:13:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"701\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/\",\"name\":\"Cinta Lombar Sem Suspens\u00f3rios - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg\",\"datePublished\":\"2023-05-30T18:33:01+00:00\",\"dateModified\":\"2026-02-06T18:13:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg\",\"width\":701,\"height\":701,\"caption\":\"Cinta Lombar\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cinta Lombar Sem Suspens\u00f3rios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cinta Lombar Sem Suspens\u00f3rios - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/910-322-3-4-5\/","og_locale":"en_GB","og_type":"article","og_title":"Cinta Lombar Sem Suspens\u00f3rios - NorSafe","og_description":"Cinta LombarCinta lombar fabricada em poli&eacute;ster com spandex para exercer a resist&ecirc;ncia adequada.Apoio traseiro em PP (polipropileno) com fecho de velcro (de nylon) para maior prote&ccedil;&atilde;o da zona lombar.Proporciona suporte na parte inferior das costas e no abd&oacute;men, permitindo liberdade de movimentos e m&aacute;ximo conforto, gra&ccedil;as &agrave; sua forma anat&oacute;mica.Sem suspens&oacute;rios.Incorpora fecho com velcro assim como tensor de ajuste tamb&eacute;m com velcro.Desta forma, oferece maior fixa&ccedil;&atilde;o e mobilidade.Lav&aacute;vel e transpir&aacute;vel. Suporte din&acirc;mico e flex&iacute;vel que n&atilde;o impede o movimento. Sem partes mec&acirc;nicas que possam estragar-se ou que tenham que ser combinadas. Incorpora quatro espartilhos.CE. Fabricada em conformidade com as exig&ecirc;ncias essenciais de sanidade e de seguran&ccedil;a especificadas no Regulamento (UE) 2016\/425","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/910-322-3-4-5\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T18:13:55+00:00","og_image":[{"width":701,"height":701,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/","name":"Cinta Lombar Sem Suspens\u00f3rios - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg","datePublished":"2023-05-30T18:33:01+00:00","dateModified":"2026-02-06T18:13:55+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_910-322-3-4-5.jpg","width":701,"height":701,"caption":"Cinta Lombar"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/910-322-3-4-5\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Cinta Lombar Sem Suspens\u00f3rios"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/310629"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=310629"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/361762"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=310629"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=310629"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=310629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}