{"id":311653,"date":"2023-05-30T19:41:28","date_gmt":"2023-05-30T18:41:28","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/corda-bungee-tool-lanyard-peso-max-5-kg\/"},"modified":"2026-02-06T19:09:47","modified_gmt":"2026-02-06T19:09:47","slug":"101372","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101372\/","title":{"rendered":"Bungee Tool Lanyard for Tools Max Weight 5 kg"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Corda Bungee Tool Lanyard p\/ Ferramentas Peso M&aacute;x 5 kg<\/p>\n<p>Corda para Ferramentas Peso M&aacute;x 5 kg e alcan&ccedil;a at&eacute; 2 m, permitindo que ferramentas mais pesadas sejam conectadas aos pontos de ancoragem, tanto dentro quanto fora do usu&aacute;rio.<br \/>Com Mosquet&atilde;o de alum&iacute;nio leve, totalmente anodizado (resistente ao atrito e abras&atilde;o) com mecanismo girat&oacute;rio anti-emaranhamento.<\/p>\n<p>Estende-se 80 cm a 120 cm.<br \/>Peso : 90 Grs.<br \/>Capacidade para suportar ferramentas at&eacute; 5kg.<\/p>\n<p>ANSI\/ISEA 121-2018.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Corda Bungee Tool Lanyard p\/ Ferramentas Peso M&aacute;x 5 kg<\/p>\n<p>Corda para Ferramentas Peso M&aacute;x 5 kg e alcan&ccedil;a at&eacute; 2 m, permitindo que ferramentas mais pesadas sejam conectadas aos pontos de ancoragem, tanto dentro quanto fora do usu&aacute;rio.<br \/>Com Mosquet&atilde;o de alum&iacute;nio leve, totalmente anodizado (resistente ao atrito e abras&atilde;o) com mecanismo girat&oacute;rio anti-emaranhamento.<\/p>\n<p>Estende-se 80 cm a 120 cm.<br \/>Peso : 90 Grs.<br \/>Capacidade para suportar ferramentas at&eacute; 5kg.<\/p>\n<p>ANSI\/ISEA 121-2018.<\/p>\n<\/div>","protected":false},"featured_media":373607,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2733],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101372\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Corda Bungee Tool Lanyard p\/ Ferramentas Peso M&aacute;x 5 kgCorda para Ferramentas Peso M&aacute;x 5 kg e alcan&ccedil;a at&eacute; 2 m, permitindo que ferramentas mais pesadas sejam conectadas aos pontos de ancoragem, tanto dentro quanto fora do usu&aacute;rio.Com Mosquet&atilde;o de alum&iacute;nio leve, totalmente anodizado (resistente ao atrito e abras&atilde;o) com mecanismo girat&oacute;rio anti-emaranhamento.Estende-se 80 cm a 120 cm.Peso : 90 Grs.Capacidade para suportar ferramentas at&eacute; 5kg.ANSI\/ISEA 121-2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101372\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T19:09:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/\",\"name\":\"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg\",\"datePublished\":\"2023-05-30T18:41:28+00:00\",\"dateModified\":\"2026-02-06T19:09:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg\",\"width\":700,\"height\":700,\"caption\":\"Corda Bungee Tool Lanyard p\/ Ferramentas Peso M\u00e1x 5 kg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101372\/","og_locale":"en_GB","og_type":"article","og_title":"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg - NorSafe","og_description":"Corda Bungee Tool Lanyard p\/ Ferramentas Peso M&aacute;x 5 kgCorda para Ferramentas Peso M&aacute;x 5 kg e alcan&ccedil;a at&eacute; 2 m, permitindo que ferramentas mais pesadas sejam conectadas aos pontos de ancoragem, tanto dentro quanto fora do usu&aacute;rio.Com Mosquet&atilde;o de alum&iacute;nio leve, totalmente anodizado (resistente ao atrito e abras&atilde;o) com mecanismo girat&oacute;rio anti-emaranhamento.Estende-se 80 cm a 120 cm.Peso : 90 Grs.Capacidade para suportar ferramentas at&eacute; 5kg.ANSI\/ISEA 121-2018.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101372\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T19:09:47+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/","name":"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg","datePublished":"2023-05-30T18:41:28+00:00","dateModified":"2026-02-06T19:09:47+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101372.jpg","width":700,"height":700,"caption":"Corda Bungee Tool Lanyard p\/ Ferramentas Peso M\u00e1x 5 kg"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101372\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Corda Bungee Tool Lanyard Peso M\u00e1x 5 kg"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/311653"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=311653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/373607"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=311653"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=311653"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=311653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}