{"id":311681,"date":"2023-05-30T19:41:42","date_gmt":"2023-05-30T18:41:42","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/corda-go-bungee-tool-lanyard-peso-max-3kg\/"},"modified":"2026-02-06T19:11:01","modified_gmt":"2026-02-06T19:11:01","slug":"101518","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101518\/","title":{"rendered":"Go Bungee Tool Lanyard for Tool. Max Weight 3Kg."},"content":{"rendered":"<div class=\"translation-block\">\n<p>Corda Go Bungee Tool Lanyard p\/ Ferram. Peso M&aacute;x 3Kg.<\/p>\n<p>Vem com um mosquet&atilde;o de dupla a&ccedil;&atilde;o resistente e uma al&ccedil;a de cabo para que possa ser facilmente conectado a todas as ferramentas manuais comuns e tem uma resist&ecirc;ncia ao estiramento muito baixa para torn&aacute;-lo confort&aacute;vel para uso durante todo o dia.<\/p>\n<p>Com Mosquet&atilde;o de alum&iacute;nio leve e anodizado (evita atrito e desgaste r&aacute;pido com  travamento seguro de alto desempenho para evitar aberturas acidentais.<\/p>\n<p>Extende de 70cm  at&eacute; 120cm.<br \/>Peso : 55 Grs.<br \/>Capacidade para suportar ferramentas at&eacute; 3kg.<\/p>\n<p>ANSI\/ISEA 121-2018.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Corda Go Bungee Tool Lanyard p\/ Ferram. Peso M&aacute;x 3Kg.<\/p>\n<p>Vem com um mosquet&atilde;o de dupla a&ccedil;&atilde;o resistente e uma al&ccedil;a de cabo para que possa ser facilmente conectado a todas as ferramentas manuais comuns e tem uma resist&ecirc;ncia ao estiramento muito baixa para torn&aacute;-lo confort&aacute;vel para uso durante todo o dia.<\/p>\n<p>Com Mosquet&atilde;o de alum&iacute;nio leve e anodizado (evita atrito e desgaste r&aacute;pido com  travamento seguro de alto desempenho para evitar aberturas acidentais.<\/p>\n<p>Extende de 70cm  at&eacute; 120cm.<br \/>Peso : 55 Grs.<br \/>Capacidade para suportar ferramentas at&eacute; 3kg.<\/p>\n<p>ANSI\/ISEA 121-2018.<\/p>\n<\/div>","protected":false},"featured_media":395798,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2733],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101518\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Corda Go Bungee Tool Lanyard p\/ Ferram. Peso M&aacute;x 3Kg.Vem com um mosquet&atilde;o de dupla a&ccedil;&atilde;o resistente e uma al&ccedil;a de cabo para que possa ser facilmente conectado a todas as ferramentas manuais comuns e tem uma resist&ecirc;ncia ao estiramento muito baixa para torn&aacute;-lo confort&aacute;vel para uso durante todo o dia.Com Mosquet&atilde;o de alum&iacute;nio leve e anodizado (evita atrito e desgaste r&aacute;pido com travamento seguro de alto desempenho para evitar aberturas acidentais.Extende de 70cm at&eacute; 120cm.Peso : 55 Grs.Capacidade para suportar ferramentas at&eacute; 3kg.ANSI\/ISEA 121-2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101518\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T19:11:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/\",\"name\":\"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg\",\"datePublished\":\"2023-05-30T18:41:42+00:00\",\"dateModified\":\"2026-02-06T19:11:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg\",\"width\":700,\"height\":700,\"caption\":\"Corda Go Bungee Tool Lanyard p\/ Ferram. Peso M\u00e1x 3Kg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101518\/","og_locale":"en_GB","og_type":"article","og_title":"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg - NorSafe","og_description":"Corda Go Bungee Tool Lanyard p\/ Ferram. Peso M&aacute;x 3Kg.Vem com um mosquet&atilde;o de dupla a&ccedil;&atilde;o resistente e uma al&ccedil;a de cabo para que possa ser facilmente conectado a todas as ferramentas manuais comuns e tem uma resist&ecirc;ncia ao estiramento muito baixa para torn&aacute;-lo confort&aacute;vel para uso durante todo o dia.Com Mosquet&atilde;o de alum&iacute;nio leve e anodizado (evita atrito e desgaste r&aacute;pido com travamento seguro de alto desempenho para evitar aberturas acidentais.Extende de 70cm at&eacute; 120cm.Peso : 55 Grs.Capacidade para suportar ferramentas at&eacute; 3kg.ANSI\/ISEA 121-2018.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/101518\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T19:11:01+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/","name":"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg","datePublished":"2023-05-30T18:41:42+00:00","dateModified":"2026-02-06T19:11:01+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_101518.jpg","width":700,"height":700,"caption":"Corda Go Bungee Tool Lanyard p\/ Ferram. Peso M\u00e1x 3Kg"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/101518\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Corda Go Bungee Tool Lanyard Peso M\u00e1x 3Kg"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/311681"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=311681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/395798"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=311681"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=311681"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=311681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}