{"id":313677,"date":"2023-05-30T20:04:59","date_gmt":"2023-05-30T19:04:59","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/luvas-juba-anticorte-c-fibra-k-rock-revestida-c-poliuretano\/"},"modified":"2026-02-06T22:18:03","modified_gmt":"2026-02-06T22:18:03","slug":"4213","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/4213\/","title":{"rendered":"Juba Anti-cut Gloves with K-Rock\u00ae 4213"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Luvas Juba Anticorte C\/Fibra K-Rock&reg; Revestida C\/Poliuretano 4213<br \/>Oferece altos n&iacute;veis de resist&ecirc;ncia mec&acirc;nica, boa ader&ecirc;ncia e toque com alto n&iacute;vel de conforto do usu&aacute;rio.<br \/>Eles fornecem um toque excelente.<br \/>Leveza e flexibilidade.<br \/>Sensa&ccedil;&atilde;o de frescura devido &agrave; sua grande respirabilidade.<br \/>Boa ader&ecirc;ncia em ambientes secos, ligeiramente &uacute;midos ou oleosos.<br \/>Excelente resist&ecirc;ncia &agrave; abras&atilde;o.<br \/>Maior durabilidade.<\/p>\n<p>Usos:<br \/>Manuseio de materiais e objetos que impliquem risco de corte, tanto em ambiente seco como levemente &uacute;mido.<br \/>Adequado para autom&oacute;veis.<br \/>Montagem de eletrodom&eacute;sticos.<br \/>Aeron&aacute;utica.<br \/>Manuten&ccedil;&atilde;o de instala&ccedil;&otilde;es e edif&iacute;cios.<br \/>Obras com movimenta&ccedil;&atilde;o de perfis, cer&acirc;micas e vidros.<br \/>Processos de fabrica&ccedil;&atilde;o de chapas e chapas de a&ccedil;o.<br \/>Estampagem de pe&ccedil;as met&aacute;licas.<\/p>\n<p>EN 388:2016+A1:2018 &#8211; 4X44E<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Luvas Juba Anticorte C\/Fibra K-Rock&reg; Revestida C\/Poliuretano 4213<br \/>Oferece altos n&iacute;veis de resist&ecirc;ncia mec&acirc;nica, boa ader&ecirc;ncia e toque com alto n&iacute;vel de conforto do usu&aacute;rio.<br \/>Eles fornecem um toque excelente.<br \/>Leveza e flexibilidade.<br \/>Sensa&ccedil;&atilde;o de frescura devido &agrave; sua grande respirabilidade.<br \/>Boa ader&ecirc;ncia em ambientes secos, ligeiramente &uacute;midos ou oleosos.<br \/>Excelente resist&ecirc;ncia &agrave; abras&atilde;o.<br \/>Maior durabilidade.<\/p>\n<p>Usos:<br \/>Manuseio de materiais e objetos que impliquem risco de corte, tanto em ambiente seco como levemente &uacute;mido.<br \/>Adequado para autom&oacute;veis.<br \/>Montagem de eletrodom&eacute;sticos.<br \/>Aeron&aacute;utica.<br \/>Manuten&ccedil;&atilde;o de instala&ccedil;&otilde;es e edif&iacute;cios.<br \/>Obras com movimenta&ccedil;&atilde;o de perfis, cer&acirc;micas e vidros.<br \/>Processos de fabrica&ccedil;&atilde;o de chapas e chapas de a&ccedil;o.<br \/>Estampagem de pe&ccedil;as met&aacute;licas.<\/p>\n<p>EN 388:2016+A1:2018 &#8211; 4X44E<\/p>\n<\/div>","protected":false},"featured_media":396488,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2749,2747],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/4213\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Luvas Juba Anticorte C\/Fibra K-Rock&reg; Revestida C\/Poliuretano 4213Oferece altos n&iacute;veis de resist&ecirc;ncia mec&acirc;nica, boa ader&ecirc;ncia e toque com alto n&iacute;vel de conforto do usu&aacute;rio.Eles fornecem um toque excelente.Leveza e flexibilidade.Sensa&ccedil;&atilde;o de frescura devido &agrave; sua grande respirabilidade.Boa ader&ecirc;ncia em ambientes secos, ligeiramente &uacute;midos ou oleosos.Excelente resist&ecirc;ncia &agrave; abras&atilde;o.Maior durabilidade.Usos:Manuseio de materiais e objetos que impliquem risco de corte, tanto em ambiente seco como levemente &uacute;mido.Adequado para autom&oacute;veis.Montagem de eletrodom&eacute;sticos.Aeron&aacute;utica.Manuten&ccedil;&atilde;o de instala&ccedil;&otilde;es e edif&iacute;cios.Obras com movimenta&ccedil;&atilde;o de perfis, cer&acirc;micas e vidros.Processos de fabrica&ccedil;&atilde;o de chapas e chapas de a&ccedil;o.Estampagem de pe&ccedil;as met&aacute;licas.EN 388:2016+A1:2018 - 4X44E\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/4213\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T22:18:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1081\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/\",\"name\":\"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg\",\"datePublished\":\"2023-05-30T19:04:59+00:00\",\"dateModified\":\"2026-02-06T22:18:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg\",\"width\":1081,\"height\":1080,\"caption\":\"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/4213\/","og_locale":"en_GB","og_type":"article","og_title":"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano - NorSafe","og_description":"Luvas Juba Anticorte C\/Fibra K-Rock&reg; Revestida C\/Poliuretano 4213Oferece altos n&iacute;veis de resist&ecirc;ncia mec&acirc;nica, boa ader&ecirc;ncia e toque com alto n&iacute;vel de conforto do usu&aacute;rio.Eles fornecem um toque excelente.Leveza e flexibilidade.Sensa&ccedil;&atilde;o de frescura devido &agrave; sua grande respirabilidade.Boa ader&ecirc;ncia em ambientes secos, ligeiramente &uacute;midos ou oleosos.Excelente resist&ecirc;ncia &agrave; abras&atilde;o.Maior durabilidade.Usos:Manuseio de materiais e objetos que impliquem risco de corte, tanto em ambiente seco como levemente &uacute;mido.Adequado para autom&oacute;veis.Montagem de eletrodom&eacute;sticos.Aeron&aacute;utica.Manuten&ccedil;&atilde;o de instala&ccedil;&otilde;es e edif&iacute;cios.Obras com movimenta&ccedil;&atilde;o de perfis, cer&acirc;micas e vidros.Processos de fabrica&ccedil;&atilde;o de chapas e chapas de a&ccedil;o.Estampagem de pe&ccedil;as met&aacute;licas.EN 388:2016+A1:2018 - 4X44E","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/4213\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T22:18:03+00:00","og_image":[{"width":1081,"height":1080,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/","name":"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg","datePublished":"2023-05-30T19:04:59+00:00","dateModified":"2026-02-06T22:18:03+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_4213.jpg","width":1081,"height":1080,"caption":"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/4213\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Luvas Juba Anticorte C\/Fibra K-Rock\u00ae Revestida C\/Poliuretano"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/313677"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=313677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/396488"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=313677"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=313677"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=313677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}