{"id":315755,"date":"2023-05-30T20:23:32","date_gmt":"2023-05-30T19:23:32","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/polo-combinado-valento-golf-m-curta-m-fecho-100alg-220grs\/"},"modified":"2026-02-07T00:56:22","modified_gmt":"2026-02-07T00:56:22","slug":"pologolf","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/pologolf\/","title":{"rendered":"Polo Combination Valento Golf M\/Short M\/ Zip 100%Alg.220Gr"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs<\/p>\n<p> &middot; polo com mangas curtas e desenho com faixas de cores contrastantes na gola e mangas<br \/> &middot; confeccionadas em tecido pique 100% algod&atilde;o, suave e confort&aacute;vel<br \/> &middot; colarinho com fecho central de meio-z&iacute;per para ventila&ccedil;&atilde;o adicional<br \/> &middot; colarinho tricot e punhos de mangas que encaixam confortavelmente<br \/> &middot; costura dupla na bainha para maior resist&ecirc;ncia e aberturas laterais para maior conforto<br \/> &middot; inclui bolso para costura, m&eacute;todos adequados de marca&ccedil;&atilde;o: estampagem, bordado, transfer, patchs, etc<br \/> &middot; ideal para diferentes usos: trabalho, promocional, desportivo e casual<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs<\/p>\n<p> &middot; polo com mangas curtas e desenho com faixas de cores contrastantes na gola e mangas<br \/> &middot; confeccionadas em tecido pique 100% algod&atilde;o, suave e confort&aacute;vel<br \/> &middot; colarinho com fecho central de meio-z&iacute;per para ventila&ccedil;&atilde;o adicional<br \/> &middot; colarinho tricot e punhos de mangas que encaixam confortavelmente<br \/> &middot; costura dupla na bainha para maior resist&ecirc;ncia e aberturas laterais para maior conforto<br \/> &middot; inclui bolso para costura, m&eacute;todos adequados de marca&ccedil;&atilde;o: estampagem, bordado, transfer, patchs, etc<br \/> &middot; ideal para diferentes usos: trabalho, promocional, desportivo e casual<\/p>\n<\/div>","protected":false},"featured_media":396956,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2763],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/pologolf\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs &middot; polo com mangas curtas e desenho com faixas de cores contrastantes na gola e mangas &middot; confeccionadas em tecido pique 100% algod&atilde;o, suave e confort&aacute;vel &middot; colarinho com fecho central de meio-z&iacute;per para ventila&ccedil;&atilde;o adicional &middot; colarinho tricot e punhos de mangas que encaixam confortavelmente &middot; costura dupla na bainha para maior resist&ecirc;ncia e aberturas laterais para maior conforto &middot; inclui bolso para costura, m&eacute;todos adequados de marca&ccedil;&atilde;o: estampagem, bordado, transfer, patchs, etc &middot; ideal para diferentes usos: trabalho, promocional, desportivo e casual\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/pologolf\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-07T00:56:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"701\" \/>\n\t<meta property=\"og:image:height\" content=\"701\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/\",\"name\":\"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg\",\"datePublished\":\"2023-05-30T19:23:32+00:00\",\"dateModified\":\"2026-02-07T00:56:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg\",\"width\":701,\"height\":701,\"caption\":\"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/pologolf\/","og_locale":"en_GB","og_type":"article","og_title":"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs - NorSafe","og_description":"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs &middot; polo com mangas curtas e desenho com faixas de cores contrastantes na gola e mangas &middot; confeccionadas em tecido pique 100% algod&atilde;o, suave e confort&aacute;vel &middot; colarinho com fecho central de meio-z&iacute;per para ventila&ccedil;&atilde;o adicional &middot; colarinho tricot e punhos de mangas que encaixam confortavelmente &middot; costura dupla na bainha para maior resist&ecirc;ncia e aberturas laterais para maior conforto &middot; inclui bolso para costura, m&eacute;todos adequados de marca&ccedil;&atilde;o: estampagem, bordado, transfer, patchs, etc &middot; ideal para diferentes usos: trabalho, promocional, desportivo e casual","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/pologolf\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-07T00:56:22+00:00","og_image":[{"width":701,"height":701,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/","name":"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg","datePublished":"2023-05-30T19:23:32+00:00","dateModified":"2026-02-07T00:56:22+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_pologolf.jpg","width":701,"height":701,"caption":"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/pologolf\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Polo Combinado Valento Golf M\/Curta M\/ Fecho 100%Alg.220Grs"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/315755"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=315755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/396956"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=315755"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=315755"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=315755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}