{"id":447299,"date":"2024-02-29T02:49:44","date_gmt":"2024-02-29T02:49:44","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/luvas-gionny-control-x1-anti-corte-latex-rugoso\/"},"modified":"2026-03-12T12:26:15","modified_gmt":"2026-03-12T12:26:15","slug":"controlx1","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/controlx1\/","title":{"rendered":"Rough Latex Anti-Cut Gloves 7032"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Luva em malha de algod&atilde;o impregnada de latex rugoso sem costura.<br \/>Luva de poli&eacute;ster de malha sem costura com um revestimento de l&aacute;tex &aacute;spero sobre a palma e os dedos.<br \/>Esta luva oferece excelente ader&ecirc;ncia em condi&ccedil;&otilde;es de umidade.<br \/>Ideal para manipula&ccedil;&atilde;o de objectos cortantes e perfurantes.<br \/>N&iacute;vel resist&ecirc;ncia mec&acirc;nica: 2 1 4 3<\/p>\n<p>EN 420:2003+A1:2009<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Luva em malha de algod&atilde;o impregnada de latex rugoso sem costura.<br \/>Luva de poli&eacute;ster de malha sem costura com um revestimento de l&aacute;tex &aacute;spero sobre a palma e os dedos.<br \/>Esta luva oferece excelente ader&ecirc;ncia em condi&ccedil;&otilde;es de umidade.<br \/>Ideal para manipula&ccedil;&atilde;o de objectos cortantes e perfurantes.<br \/>N&iacute;vel resist&ecirc;ncia mec&acirc;nica: 2 1 4 3<\/p>\n<p>EN 420:2003+A1:2009<\/p>\n<\/div>","protected":false},"featured_media":447296,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2749,2747],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luvas Gionny Control X1 Anti-Corte Latex Rugoso - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/controlx1\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luvas Gionny Control X1 Anti-Corte Latex Rugoso - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Luva em malha de algod&atilde;o impregnada de latex rugoso sem costura.Luva de poli&eacute;ster de malha sem costura com um revestimento de l&aacute;tex &aacute;spero sobre a palma e os dedos.Esta luva oferece excelente ader&ecirc;ncia em condi&ccedil;&otilde;es de umidade.Ideal para manipula&ccedil;&atilde;o de objectos cortantes e perfurantes.N&iacute;vel resist&ecirc;ncia mec&acirc;nica: 2 1 4 3EN 420:2003+A1:2009\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/controlx1\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T12:26:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/\",\"name\":\"Luvas Gionny Control X1 Anti-Corte Latex Rugoso - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg\",\"datePublished\":\"2024-02-29T02:49:44+00:00\",\"dateModified\":\"2026-03-12T12:26:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg\",\"width\":700,\"height\":700,\"caption\":\"Luvas Gionny Control X1 Anti-Corte Latex Rugoso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luvas Gionny Control X1 Anti-Corte Latex Rugoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luvas Gionny Control X1 Anti-Corte Latex Rugoso - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/controlx1\/","og_locale":"en_GB","og_type":"article","og_title":"Luvas Gionny Control X1 Anti-Corte Latex Rugoso - NorSafe","og_description":"Luva em malha de algod&atilde;o impregnada de latex rugoso sem costura.Luva de poli&eacute;ster de malha sem costura com um revestimento de l&aacute;tex &aacute;spero sobre a palma e os dedos.Esta luva oferece excelente ader&ecirc;ncia em condi&ccedil;&otilde;es de umidade.Ideal para manipula&ccedil;&atilde;o de objectos cortantes e perfurantes.N&iacute;vel resist&ecirc;ncia mec&acirc;nica: 2 1 4 3EN 420:2003+A1:2009","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/controlx1\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-03-12T12:26:15+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/","name":"Luvas Gionny Control X1 Anti-Corte Latex Rugoso - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg","datePublished":"2024-02-29T02:49:44+00:00","dateModified":"2026-03-12T12:26:15+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_controlx1.jpg","width":700,"height":700,"caption":"Luvas Gionny Control X1 Anti-Corte Latex Rugoso"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/controlx1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Luvas Gionny Control X1 Anti-Corte Latex Rugoso"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/447299"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=447299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/447296"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=447299"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=447299"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=447299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}