{"id":506191,"date":"2024-05-07T02:44:09","date_gmt":"2024-05-07T01:44:09","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/fato-macaco-ignifugo-anti-estatico-c-fita-reflectora-280-grs-2\/"},"modified":"2026-02-06T20:13:08","modified_gmt":"2026-02-06T20:13:08","slug":"mv28","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/mv28\/","title":{"rendered":"Anti-Static Fire-Reflective Multinorm Suit w\/reflective tape"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Fato-Macaco Portwest Ign&iacute;fugo Anti Est&aacute;tico AV<\/p>\n<p>O tecido modacr&iacute;lico de dois tons, juntamente com as faixas reflectoras, fornece ao utilizador visibilidade avan&ccedil;ada e protec&ccedil;&atilde;o total em situa&ccedil;&otilde;es perigosas.<br \/>O design aprimorado atende aos requisitos rigorosos da protec&ccedil;&atilde;o Arc Flash.<br \/>Protec&ccedil;&atilde;o contra calor radiante, convectivo e de contacto.<br \/>Bolso traseiro.<br \/>Bolso para o metro.<br \/>Costuras triplas para maior durabilidade.<br \/>Costas com Fole para uma maior liberdade de movimento.<br \/>Punhos ajust&aacute;veis por fita aderente.<br \/>Padr&atilde;o Fita de movimento Bio para melhorar o reconhecimento da forma humana &agrave; dist&acirc;ncia.<br \/>Fita cosida industrial resistente &agrave;s chamas.<br \/>Bolsos para joelheiras com 2 n&iacute;veis permitindo duas op&ccedil;&otilde;es de posicionamento.<br \/>La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.<br \/>Fecho de correr frontal de lat&atilde;o dur&aacute;vel de duas vias para f&aacute;cil acesso.<br \/>8 bolsos para armazenamento amplo.<br \/>Certificado CE.<br \/>CE-CAT III.<br \/>Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Fato-Macaco Portwest Ign&iacute;fugo Anti Est&aacute;tico AV<\/p>\n<p>O tecido modacr&iacute;lico de dois tons, juntamente com as faixas reflectoras, fornece ao utilizador visibilidade avan&ccedil;ada e protec&ccedil;&atilde;o total em situa&ccedil;&otilde;es perigosas.<br \/>O design aprimorado atende aos requisitos rigorosos da protec&ccedil;&atilde;o Arc Flash.<br \/>Protec&ccedil;&atilde;o contra calor radiante, convectivo e de contacto.<br \/>Bolso traseiro.<br \/>Bolso para o metro.<br \/>Costuras triplas para maior durabilidade.<br \/>Costas com Fole para uma maior liberdade de movimento.<br \/>Punhos ajust&aacute;veis por fita aderente.<br \/>Padr&atilde;o Fita de movimento Bio para melhorar o reconhecimento da forma humana &agrave; dist&acirc;ncia.<br \/>Fita cosida industrial resistente &agrave;s chamas.<br \/>Bolsos para joelheiras com 2 n&iacute;veis permitindo duas op&ccedil;&otilde;es de posicionamento.<br \/>La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.<br \/>Fecho de correr frontal de lat&atilde;o dur&aacute;vel de duas vias para f&aacute;cil acesso.<br \/>8 bolsos para armazenamento amplo.<br \/>Certificado CE.<br \/>CE-CAT III.<br \/>Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.<\/p>\n<\/div>","protected":false},"featured_media":506188,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2747,2754],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/mv28\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Fato-Macaco Portwest Ign&iacute;fugo Anti Est&aacute;tico AVO tecido modacr&iacute;lico de dois tons, juntamente com as faixas reflectoras, fornece ao utilizador visibilidade avan&ccedil;ada e protec&ccedil;&atilde;o total em situa&ccedil;&otilde;es perigosas.O design aprimorado atende aos requisitos rigorosos da protec&ccedil;&atilde;o Arc Flash.Protec&ccedil;&atilde;o contra calor radiante, convectivo e de contacto.Bolso traseiro.Bolso para o metro.Costuras triplas para maior durabilidade.Costas com Fole para uma maior liberdade de movimento.Punhos ajust&aacute;veis por fita aderente.Padr&atilde;o Fita de movimento Bio para melhorar o reconhecimento da forma humana &agrave; dist&acirc;ncia.Fita cosida industrial resistente &agrave;s chamas.Bolsos para joelheiras com 2 n&iacute;veis permitindo duas op&ccedil;&otilde;es de posicionamento.La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.Fecho de correr frontal de lat&atilde;o dur&aacute;vel de duas vias para f&aacute;cil acesso.8 bolsos para armazenamento amplo.Certificado CE.CE-CAT III.Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/mv28\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T20:13:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/\",\"name\":\"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg\",\"datePublished\":\"2024-05-07T01:44:09+00:00\",\"dateModified\":\"2026-02-06T20:13:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg\",\"width\":700,\"height\":700,\"caption\":\"Fato-Macaco Portwest Ign\u00edfugo Anti Est\u00e1tico AV\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/mv28\/","og_locale":"en_GB","og_type":"article","og_title":"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs - NorSafe","og_description":"Fato-Macaco Portwest Ign&iacute;fugo Anti Est&aacute;tico AVO tecido modacr&iacute;lico de dois tons, juntamente com as faixas reflectoras, fornece ao utilizador visibilidade avan&ccedil;ada e protec&ccedil;&atilde;o total em situa&ccedil;&otilde;es perigosas.O design aprimorado atende aos requisitos rigorosos da protec&ccedil;&atilde;o Arc Flash.Protec&ccedil;&atilde;o contra calor radiante, convectivo e de contacto.Bolso traseiro.Bolso para o metro.Costuras triplas para maior durabilidade.Costas com Fole para uma maior liberdade de movimento.Punhos ajust&aacute;veis por fita aderente.Padr&atilde;o Fita de movimento Bio para melhorar o reconhecimento da forma humana &agrave; dist&acirc;ncia.Fita cosida industrial resistente &agrave;s chamas.Bolsos para joelheiras com 2 n&iacute;veis permitindo duas op&ccedil;&otilde;es de posicionamento.La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.Fecho de correr frontal de lat&atilde;o dur&aacute;vel de duas vias para f&aacute;cil acesso.8 bolsos para armazenamento amplo.Certificado CE.CE-CAT III.Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/mv28\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T20:13:08+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/","name":"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg","datePublished":"2024-05-07T01:44:09+00:00","dateModified":"2026-02-06T20:13:08+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_mv28.jpg","width":700,"height":700,"caption":"Fato-Macaco Portwest Ign\u00edfugo Anti Est\u00e1tico AV"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/mv28\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Fato-Macaco Ign\u00edfugo Anti-Est\u00e1tico C\/fita reflectora | 280 grs"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/506191"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=506191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/506188"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=506191"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=506191"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=506191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}