{"id":596484,"date":"2024-09-27T02:41:14","date_gmt":"2024-09-27T01:41:14","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/corda-semi-estatica-petzl-segment-8mm-branca-50mt\/"},"modified":"2026-02-06T19:15:10","modified_gmt":"2026-02-06T19:15:10","slug":"r076aa00","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/r076aa00\/","title":{"rendered":"Petzl SEGMENT 8mm White Semi-Static Rope 50mt"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Corda Semi-Est&aacute;tica Petzl SEGMENT 8mm Branca 50mt<\/p>\n<p>Desempenho consistente ao longo do tempo.<br \/>Constru&ccedil;&atilde;o EverFlex com n&uacute;cleo de nylon e bainha de poli&eacute;ster.<br \/>Garante grande flexibilidade ao longo do tempo e sob quaisquer condi&ccedil;&otilde;es (&aacute;gua, poeira, lama&#8230;), permitindo manter um excelente manuseio a longo prazo.<br \/>Comprimento: 50 metros<br \/>Personaliza&ccedil;&atilde;o mediante solicita&ccedil;&atilde;o: possibilidade de encomendar uma corda de comprimento espec&iacute;fico (at&eacute; 2000 m)<br \/>Di&acirc;metro: 8 mm.<br \/>Material(ais): poli&eacute;ster, nylon.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Corda Semi-Est&aacute;tica Petzl SEGMENT 8mm Branca 50mt<\/p>\n<p>Desempenho consistente ao longo do tempo.<br \/>Constru&ccedil;&atilde;o EverFlex com n&uacute;cleo de nylon e bainha de poli&eacute;ster.<br \/>Garante grande flexibilidade ao longo do tempo e sob quaisquer condi&ccedil;&otilde;es (&aacute;gua, poeira, lama&#8230;), permitindo manter um excelente manuseio a longo prazo.<br \/>Comprimento: 50 metros<br \/>Personaliza&ccedil;&atilde;o mediante solicita&ccedil;&atilde;o: possibilidade de encomendar uma corda de comprimento espec&iacute;fico (at&eacute; 2000 m)<br \/>Di&acirc;metro: 8 mm.<br \/>Material(ais): poli&eacute;ster, nylon.<\/p>\n<\/div>","protected":false},"featured_media":596481,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2733],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/r076aa00\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Corda Semi-Est&aacute;tica Petzl SEGMENT 8mm Branca 50mtDesempenho consistente ao longo do tempo.Constru&ccedil;&atilde;o EverFlex com n&uacute;cleo de nylon e bainha de poli&eacute;ster.Garante grande flexibilidade ao longo do tempo e sob quaisquer condi&ccedil;&otilde;es (&aacute;gua, poeira, lama...), permitindo manter um excelente manuseio a longo prazo.Comprimento: 50 metrosPersonaliza&ccedil;&atilde;o mediante solicita&ccedil;&atilde;o: possibilidade de encomendar uma corda de comprimento espec&iacute;fico (at&eacute; 2000 m)Di&acirc;metro: 8 mm.Material(ais): poli&eacute;ster, nylon.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/r076aa00\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T19:15:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/\",\"name\":\"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg\",\"datePublished\":\"2024-09-27T01:41:14+00:00\",\"dateModified\":\"2026-02-06T19:15:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg\",\"width\":700,\"height\":700,\"caption\":\"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/r076aa00\/","og_locale":"en_GB","og_type":"article","og_title":"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt - NorSafe","og_description":"Corda Semi-Est&aacute;tica Petzl SEGMENT 8mm Branca 50mtDesempenho consistente ao longo do tempo.Constru&ccedil;&atilde;o EverFlex com n&uacute;cleo de nylon e bainha de poli&eacute;ster.Garante grande flexibilidade ao longo do tempo e sob quaisquer condi&ccedil;&otilde;es (&aacute;gua, poeira, lama...), permitindo manter um excelente manuseio a longo prazo.Comprimento: 50 metrosPersonaliza&ccedil;&atilde;o mediante solicita&ccedil;&atilde;o: possibilidade de encomendar uma corda de comprimento espec&iacute;fico (at&eacute; 2000 m)Di&acirc;metro: 8 mm.Material(ais): poli&eacute;ster, nylon.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/r076aa00\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T19:15:10+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/","name":"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg","datePublished":"2024-09-27T01:41:14+00:00","dateModified":"2026-02-06T19:15:10+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_r076aa00.jpg","width":700,"height":700,"caption":"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/r076aa00\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Corda Semi-Est\u00e1tica Petzl SEGMENT 8mm Branca 50mt"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/596484"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=596484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/596481"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=596484"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=596484"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=596484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}