{"id":632841,"date":"2024-10-09T03:04:51","date_gmt":"2024-10-09T02:04:51","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/tenis-portwest-spli-on-trainer-s2\/"},"modified":"2026-02-08T02:40:25","modified_gmt":"2026-02-08T02:40:25","slug":"fd62","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/fd62\/","title":{"rendered":"Portwest Compositelite Slip On Safety Trainer"},"content":{"rendered":"<div class=\"translation-block\">\n<p>T&eacute;nis Portwest Compositelite Slip On Safety Trainer<\/p>\n<p>Esta Microfibra sem metal no t&ecirc;nis de seguran&ccedil;a oferece um forro antimicrobiano, palmilha e um pano limpo superior.<br \/>A silhueta deslizante ajuda a uma superf&iacute;cie facilmente limpa, reduzindo a possibilidade de contamina&ccedil;&atilde;o.<br \/>Perfeito para as ind&uacute;strias alimentar, farmac&ecirc;utica, de catering e de hospitalidade.<br \/>Gola acolchoada para maior conforto.<br \/>Limpe a parte superior.<br \/>Palmilha perfurada tratada com antibacteriano para ajudar a manter os p&eacute;s frescos e limpos.<br \/>Cal&ccedil;ado Vegan Amig&aacute;vel.<br \/>Biqueira em comp&oacute;sito para maior protec&ccedil;&atilde;o.<br \/>Superior resistente &agrave; &aacute;gua para evitar a penetra&ccedil;&atilde;o de &aacute;gua.<br \/>Livre de metal.<br \/>Cal&ccedil;ado antiest&aacute;tico.<br \/>Absor&ccedil;&atilde;o de energia na zona de apoio.<br \/>Sola exterior resistente a combust&iacute;vel e &oacute;leo.<br \/>SRC &#8211; Sola antiderrapante para evitar escorreg&otilde;es e trope&ccedil;&otilde;es em superf&iacute;cies de cer&acirc;mica e a&ccedil;o.<br \/>Unidade de Sola de Dupla Densidade.<br \/>Certificado CE.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>T&eacute;nis Portwest Compositelite Slip On Safety Trainer<\/p>\n<p>Esta Microfibra sem metal no t&ecirc;nis de seguran&ccedil;a oferece um forro antimicrobiano, palmilha e um pano limpo superior.<br \/>A silhueta deslizante ajuda a uma superf&iacute;cie facilmente limpa, reduzindo a possibilidade de contamina&ccedil;&atilde;o.<br \/>Perfeito para as ind&uacute;strias alimentar, farmac&ecirc;utica, de catering e de hospitalidade.<br \/>Gola acolchoada para maior conforto.<br \/>Limpe a parte superior.<br \/>Palmilha perfurada tratada com antibacteriano para ajudar a manter os p&eacute;s frescos e limpos.<br \/>Cal&ccedil;ado Vegan Amig&aacute;vel.<br \/>Biqueira em comp&oacute;sito para maior protec&ccedil;&atilde;o.<br \/>Superior resistente &agrave; &aacute;gua para evitar a penetra&ccedil;&atilde;o de &aacute;gua.<br \/>Livre de metal.<br \/>Cal&ccedil;ado antiest&aacute;tico.<br \/>Absor&ccedil;&atilde;o de energia na zona de apoio.<br \/>Sola exterior resistente a combust&iacute;vel e &oacute;leo.<br \/>SRC &#8211; Sola antiderrapante para evitar escorreg&otilde;es e trope&ccedil;&otilde;es em superf&iacute;cies de cer&acirc;mica e a&ccedil;o.<br \/>Unidade de Sola de Dupla Densidade.<br \/>Certificado CE.<\/p>\n<\/div>","protected":false},"featured_media":632838,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2748,2747],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>T\u00e9nis Portwest Spli-On Trainer S2 - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/fd62\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"T\u00e9nis Portwest Spli-On Trainer S2 - NorSafe\" \/>\n<meta property=\"og:description\" content=\"T&eacute;nis Portwest Compositelite Slip On Safety TrainerEsta Microfibra sem metal no t&ecirc;nis de seguran&ccedil;a oferece um forro antimicrobiano, palmilha e um pano limpo superior.A silhueta deslizante ajuda a uma superf&iacute;cie facilmente limpa, reduzindo a possibilidade de contamina&ccedil;&atilde;o.Perfeito para as ind&uacute;strias alimentar, farmac&ecirc;utica, de catering e de hospitalidade.Gola acolchoada para maior conforto.Limpe a parte superior.Palmilha perfurada tratada com antibacteriano para ajudar a manter os p&eacute;s frescos e limpos.Cal&ccedil;ado Vegan Amig&aacute;vel.Biqueira em comp&oacute;sito para maior protec&ccedil;&atilde;o.Superior resistente &agrave; &aacute;gua para evitar a penetra&ccedil;&atilde;o de &aacute;gua.Livre de metal.Cal&ccedil;ado antiest&aacute;tico.Absor&ccedil;&atilde;o de energia na zona de apoio.Sola exterior resistente a combust&iacute;vel e &oacute;leo.SRC - Sola antiderrapante para evitar escorreg&otilde;es e trope&ccedil;&otilde;es em superf&iacute;cies de cer&acirc;mica e a&ccedil;o.Unidade de Sola de Dupla Densidade.Certificado CE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/fd62\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-08T02:40:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/\",\"name\":\"T\u00e9nis Portwest Spli-On Trainer S2 - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg\",\"datePublished\":\"2024-10-09T02:04:51+00:00\",\"dateModified\":\"2026-02-08T02:40:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg\",\"width\":700,\"height\":700,\"caption\":\"T\u00e9nis Portwest Spli-On Trainer S2 SRC\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00e9nis Portwest Spli-On Trainer S2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9nis Portwest Spli-On Trainer S2 - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/fd62\/","og_locale":"en_GB","og_type":"article","og_title":"T\u00e9nis Portwest Spli-On Trainer S2 - NorSafe","og_description":"T&eacute;nis Portwest Compositelite Slip On Safety TrainerEsta Microfibra sem metal no t&ecirc;nis de seguran&ccedil;a oferece um forro antimicrobiano, palmilha e um pano limpo superior.A silhueta deslizante ajuda a uma superf&iacute;cie facilmente limpa, reduzindo a possibilidade de contamina&ccedil;&atilde;o.Perfeito para as ind&uacute;strias alimentar, farmac&ecirc;utica, de catering e de hospitalidade.Gola acolchoada para maior conforto.Limpe a parte superior.Palmilha perfurada tratada com antibacteriano para ajudar a manter os p&eacute;s frescos e limpos.Cal&ccedil;ado Vegan Amig&aacute;vel.Biqueira em comp&oacute;sito para maior protec&ccedil;&atilde;o.Superior resistente &agrave; &aacute;gua para evitar a penetra&ccedil;&atilde;o de &aacute;gua.Livre de metal.Cal&ccedil;ado antiest&aacute;tico.Absor&ccedil;&atilde;o de energia na zona de apoio.Sola exterior resistente a combust&iacute;vel e &oacute;leo.SRC - Sola antiderrapante para evitar escorreg&otilde;es e trope&ccedil;&otilde;es em superf&iacute;cies de cer&acirc;mica e a&ccedil;o.Unidade de Sola de Dupla Densidade.Certificado CE.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/fd62\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-08T02:40:25+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/","name":"T\u00e9nis Portwest Spli-On Trainer S2 - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg","datePublished":"2024-10-09T02:04:51+00:00","dateModified":"2026-02-08T02:40:25+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_fd62.jpg","width":700,"height":700,"caption":"T\u00e9nis Portwest Spli-On Trainer S2 SRC"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/fd62\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"T\u00e9nis Portwest Spli-On Trainer S2"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/632841"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=632841"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/632838"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=632841"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=632841"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=632841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}