{"id":722630,"date":"2025-01-10T03:05:11","date_gmt":"2025-01-10T03:05:11","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/tampao-portwest-reutilizavel-c-fio-32db-50-pares\/"},"modified":"2026-02-08T02:03:26","modified_gmt":"2026-02-08T02:03:26","slug":"ep07","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/ep07\/","title":{"rendered":"Tampao Portwest Reutilizavel C\/Fio 32dB &#8211; 50 Pares"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Tampao Portwest Reutilizavel C\/Fio 32dB &#8211; 50 Pares<\/p>\n<p>Tamp&otilde;es para os ouvidos detect&aacute;veis e reutiliz&aacute;veis em material TPR (borracha termopl&aacute;stica).<br \/>A funcionalidade detect&aacute;vel &eacute; fabricada com uma t&eacute;cnica avan&ccedil;ada, adicionando-se aparas de metal ao material TPR durante o processo de injec&ccedil;&atilde;o, sem a necessidade de adicionar a bola detect&aacute;vel de metal.<br \/>Recomendado para uso em ambientes da ind&uacute;stria alimentar.<br \/>Cada par vem dentro de um polybag higi&eacute;nico com instru&ccedil;&otilde;es de montagem.<br \/>Com cord&atilde;o para guardar.<br \/>Um par por saco pl&aacute;stico para armazenamento higi&eacute;nico.<br \/>Fornecido numa pr&aacute;tica caixa dispensadora port&aacute;til.<br \/>Desenho de flange triplo e material tpr macio para um ajuste confort&aacute;vel.<br \/>Tamp&otilde;es auriculares reutiliz&aacute;veis para apoiar a sustentabilidade.<br \/>Caixa de retalho para melhor apresenta&ccedil;&atilde;o na venda ao p&uacute;blico.<br \/>Embalado individualmente para m&aacute;quinas de venda autom&aacute;tica.<br \/>Certificado CE.<br \/>CE-CAT III.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Tampao Portwest Reutilizavel C\/Fio 32dB &#8211; 50 Pares<\/p>\n<p>Tamp&otilde;es para os ouvidos detect&aacute;veis e reutiliz&aacute;veis em material TPR (borracha termopl&aacute;stica).<br \/>A funcionalidade detect&aacute;vel &eacute; fabricada com uma t&eacute;cnica avan&ccedil;ada, adicionando-se aparas de metal ao material TPR durante o processo de injec&ccedil;&atilde;o, sem a necessidade de adicionar a bola detect&aacute;vel de metal.<br \/>Recomendado para uso em ambientes da ind&uacute;stria alimentar.<br \/>Cada par vem dentro de um polybag higi&eacute;nico com instru&ccedil;&otilde;es de montagem.<br \/>Com cord&atilde;o para guardar.<br \/>Um par por saco pl&aacute;stico para armazenamento higi&eacute;nico.<br \/>Fornecido numa pr&aacute;tica caixa dispensadora port&aacute;til.<br \/>Desenho de flange triplo e material tpr macio para um ajuste confort&aacute;vel.<br \/>Tamp&otilde;es auriculares reutiliz&aacute;veis para apoiar a sustentabilidade.<br \/>Caixa de retalho para melhor apresenta&ccedil;&atilde;o na venda ao p&uacute;blico.<br \/>Embalado individualmente para m&aacute;quinas de venda autom&aacute;tica.<br \/>Certificado CE.<br \/>CE-CAT III.<\/p>\n<\/div>","protected":false},"featured_media":722626,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2747,2751],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/ep07\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 ParesTamp&otilde;es para os ouvidos detect&aacute;veis e reutiliz&aacute;veis em material TPR (borracha termopl&aacute;stica).A funcionalidade detect&aacute;vel &eacute; fabricada com uma t&eacute;cnica avan&ccedil;ada, adicionando-se aparas de metal ao material TPR durante o processo de injec&ccedil;&atilde;o, sem a necessidade de adicionar a bola detect&aacute;vel de metal.Recomendado para uso em ambientes da ind&uacute;stria alimentar.Cada par vem dentro de um polybag higi&eacute;nico com instru&ccedil;&otilde;es de montagem.Com cord&atilde;o para guardar.Um par por saco pl&aacute;stico para armazenamento higi&eacute;nico.Fornecido numa pr&aacute;tica caixa dispensadora port&aacute;til.Desenho de flange triplo e material tpr macio para um ajuste confort&aacute;vel.Tamp&otilde;es auriculares reutiliz&aacute;veis para apoiar a sustentabilidade.Caixa de retalho para melhor apresenta&ccedil;&atilde;o na venda ao p&uacute;blico.Embalado individualmente para m&aacute;quinas de venda autom&aacute;tica.Certificado CE.CE-CAT III.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/ep07\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-08T02:03:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/\",\"name\":\"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg\",\"datePublished\":\"2025-01-10T03:05:11+00:00\",\"dateModified\":\"2026-02-08T02:03:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg\",\"width\":700,\"height\":700,\"caption\":\"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tampao Portwest Reutilizavel C\/Fio 32dB &#8211; 50 Pares\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/ep07\/","og_locale":"en_GB","og_type":"article","og_title":"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares - NorSafe","og_description":"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 ParesTamp&otilde;es para os ouvidos detect&aacute;veis e reutiliz&aacute;veis em material TPR (borracha termopl&aacute;stica).A funcionalidade detect&aacute;vel &eacute; fabricada com uma t&eacute;cnica avan&ccedil;ada, adicionando-se aparas de metal ao material TPR durante o processo de injec&ccedil;&atilde;o, sem a necessidade de adicionar a bola detect&aacute;vel de metal.Recomendado para uso em ambientes da ind&uacute;stria alimentar.Cada par vem dentro de um polybag higi&eacute;nico com instru&ccedil;&otilde;es de montagem.Com cord&atilde;o para guardar.Um par por saco pl&aacute;stico para armazenamento higi&eacute;nico.Fornecido numa pr&aacute;tica caixa dispensadora port&aacute;til.Desenho de flange triplo e material tpr macio para um ajuste confort&aacute;vel.Tamp&otilde;es auriculares reutiliz&aacute;veis para apoiar a sustentabilidade.Caixa de retalho para melhor apresenta&ccedil;&atilde;o na venda ao p&uacute;blico.Embalado individualmente para m&aacute;quinas de venda autom&aacute;tica.Certificado CE.CE-CAT III.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/ep07\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-08T02:03:26+00:00","og_image":[{"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg","width":640,"height":640,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/","name":"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg","datePublished":"2025-01-10T03:05:11+00:00","dateModified":"2026-02-08T02:03:26+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_ep07.jpg","width":700,"height":700,"caption":"Tampao Portwest Reutilizavel C\/Fio 32dB - 50 Pares"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/ep07\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Tampao Portwest Reutilizavel C\/Fio 32dB &#8211; 50 Pares"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/722630"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=722630"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/722626"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=722630"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=722630"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=722630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}