{"id":877419,"date":"2025-08-05T02:55:50","date_gmt":"2025-08-05T01:55:50","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/casaco-alta-visibilidade-portwest-3-em-1\/"},"modified":"2026-02-06T17:09:54","modified_gmt":"2026-02-06T17:09:54","slug":"c469","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/c469\/","title":{"rendered":"Portwest 3-in-1 High Visibility Jacket"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Casaco Alta Visibilidade Portwest 3 em 1<\/p>\n<p>Imperme&aacute;vel com costuras termoseladas que impedem a penetra&ccedil;&atilde;o da &aacute;gua.<br \/>Acabamento de tecido Texpel&trade; Splash Eco extremamente resistente &agrave; &aacute;gua e sem PFAS, a &aacute;gua afasta-se da superf&iacute;cie do tecido.<br \/>EN342 Protec&ccedil;&atilde;o contra o frio, certificada at&eacute; -40&deg;C.<br \/>Mangas, forro e gola em p&ecirc;lo destac&aacute;veis fornecem m&uacute;ltiplas op&ccedil;&otilde;es ao utilizador.<br \/>Punhos ajust&aacute;veis para um conforto seguro.<br \/>Punho interior de Malha.<br \/>Diversos bolsos utilit&aacute;rios.<br \/>Bolso no peito com fecho.<br \/>Bolso na manga.<br \/>Dois bolsos chapa inferiores.<br \/>Anel em D para chaves ou cart&otilde;es de identifica&ccedil;&atilde;o.<br \/>Mangas pr&eacute;-moldadas permitem uma maior liberdade de movimento.<br \/>Pain&eacute;is de contraste para protec&ccedil;&atilde;o contra sujidade.<br \/>Casaco pode ser usado de tr&ecirc;s maneiras para usos m&uacute;ltiplos.<br \/>Casaco interior amov&iacute;vel para maior versatilidade em todas as condi&ccedil;&otilde;es climat&eacute;ricas.<br \/>Fita reflectora para maior visibilidade.<br \/>10 bolsos espa&ccedil;osos.<br \/>La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.<br \/>Zip de Dupla Via para f&aacute;cil acesso.<br \/>Bolso de telem&oacute;vel.<br \/>Bolso externo para tablet para um armazenamento seguro.<br \/>Capuz destac&aacute;vel oculto.<br \/>Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.<br \/>Certificado conforme EN ISO 20471 ap&oacute;s 50 lavagens.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Casaco Alta Visibilidade Portwest 3 em 1<\/p>\n<p>Imperme&aacute;vel com costuras termoseladas que impedem a penetra&ccedil;&atilde;o da &aacute;gua.<br \/>Acabamento de tecido Texpel&trade; Splash Eco extremamente resistente &agrave; &aacute;gua e sem PFAS, a &aacute;gua afasta-se da superf&iacute;cie do tecido.<br \/>EN342 Protec&ccedil;&atilde;o contra o frio, certificada at&eacute; -40&deg;C.<br \/>Mangas, forro e gola em p&ecirc;lo destac&aacute;veis fornecem m&uacute;ltiplas op&ccedil;&otilde;es ao utilizador.<br \/>Punhos ajust&aacute;veis para um conforto seguro.<br \/>Punho interior de Malha.<br \/>Diversos bolsos utilit&aacute;rios.<br \/>Bolso no peito com fecho.<br \/>Bolso na manga.<br \/>Dois bolsos chapa inferiores.<br \/>Anel em D para chaves ou cart&otilde;es de identifica&ccedil;&atilde;o.<br \/>Mangas pr&eacute;-moldadas permitem uma maior liberdade de movimento.<br \/>Pain&eacute;is de contraste para protec&ccedil;&atilde;o contra sujidade.<br \/>Casaco pode ser usado de tr&ecirc;s maneiras para usos m&uacute;ltiplos.<br \/>Casaco interior amov&iacute;vel para maior versatilidade em todas as condi&ccedil;&otilde;es climat&eacute;ricas.<br \/>Fita reflectora para maior visibilidade.<br \/>10 bolsos espa&ccedil;osos.<br \/>La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.<br \/>Zip de Dupla Via para f&aacute;cil acesso.<br \/>Bolso de telem&oacute;vel.<br \/>Bolso externo para tablet para um armazenamento seguro.<br \/>Capuz destac&aacute;vel oculto.<br \/>Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.<br \/>Certificado conforme EN ISO 20471 ap&oacute;s 50 lavagens.<\/p>\n<\/div>","protected":false},"featured_media":877416,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2763],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Casaco Alta Visibilidade Portwest 3 em 1 - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/c469\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Casaco Alta Visibilidade Portwest 3 em 1 - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Casaco Alta Visibilidade Portwest 3 em 1Imperme&aacute;vel com costuras termoseladas que impedem a penetra&ccedil;&atilde;o da &aacute;gua.Acabamento de tecido Texpel&trade; Splash Eco extremamente resistente &agrave; &aacute;gua e sem PFAS, a &aacute;gua afasta-se da superf&iacute;cie do tecido.EN342 Protec&ccedil;&atilde;o contra o frio, certificada at&eacute; -40&deg;C.Mangas, forro e gola em p&ecirc;lo destac&aacute;veis fornecem m&uacute;ltiplas op&ccedil;&otilde;es ao utilizador.Punhos ajust&aacute;veis para um conforto seguro.Punho interior de Malha.Diversos bolsos utilit&aacute;rios.Bolso no peito com fecho.Bolso na manga.Dois bolsos chapa inferiores.Anel em D para chaves ou cart&otilde;es de identifica&ccedil;&atilde;o.Mangas pr&eacute;-moldadas permitem uma maior liberdade de movimento.Pain&eacute;is de contraste para protec&ccedil;&atilde;o contra sujidade.Casaco pode ser usado de tr&ecirc;s maneiras para usos m&uacute;ltiplos.Casaco interior amov&iacute;vel para maior versatilidade em todas as condi&ccedil;&otilde;es climat&eacute;ricas.Fita reflectora para maior visibilidade.10 bolsos espa&ccedil;osos.La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.Zip de Dupla Via para f&aacute;cil acesso.Bolso de telem&oacute;vel.Bolso externo para tablet para um armazenamento seguro.Capuz destac&aacute;vel oculto.Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.Certificado conforme EN ISO 20471 ap&oacute;s 50 lavagens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/c469\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T17:09:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/\",\"name\":\"Casaco Alta Visibilidade Portwest 3 em 1 - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg\",\"datePublished\":\"2025-08-05T01:55:50+00:00\",\"dateModified\":\"2026-02-06T17:09:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg\",\"width\":700,\"height\":700,\"caption\":\"Casaco Alta Visibilidade Portwest 3 em 1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Casaco Alta Visibilidade Portwest 3 em 1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Casaco Alta Visibilidade Portwest 3 em 1 - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/c469\/","og_locale":"en_GB","og_type":"article","og_title":"Casaco Alta Visibilidade Portwest 3 em 1 - NorSafe","og_description":"Casaco Alta Visibilidade Portwest 3 em 1Imperme&aacute;vel com costuras termoseladas que impedem a penetra&ccedil;&atilde;o da &aacute;gua.Acabamento de tecido Texpel&trade; Splash Eco extremamente resistente &agrave; &aacute;gua e sem PFAS, a &aacute;gua afasta-se da superf&iacute;cie do tecido.EN342 Protec&ccedil;&atilde;o contra o frio, certificada at&eacute; -40&deg;C.Mangas, forro e gola em p&ecirc;lo destac&aacute;veis fornecem m&uacute;ltiplas op&ccedil;&otilde;es ao utilizador.Punhos ajust&aacute;veis para um conforto seguro.Punho interior de Malha.Diversos bolsos utilit&aacute;rios.Bolso no peito com fecho.Bolso na manga.Dois bolsos chapa inferiores.Anel em D para chaves ou cart&otilde;es de identifica&ccedil;&atilde;o.Mangas pr&eacute;-moldadas permitem uma maior liberdade de movimento.Pain&eacute;is de contraste para protec&ccedil;&atilde;o contra sujidade.Casaco pode ser usado de tr&ecirc;s maneiras para usos m&uacute;ltiplos.Casaco interior amov&iacute;vel para maior versatilidade em todas as condi&ccedil;&otilde;es climat&eacute;ricas.Fita reflectora para maior visibilidade.10 bolsos espa&ccedil;osos.La&ccedil;o para f&aacute;cil fixa&ccedil;&atilde;o de um r&aacute;dio.Zip de Dupla Via para f&aacute;cil acesso.Bolso de telem&oacute;vel.Bolso externo para tablet para um armazenamento seguro.Capuz destac&aacute;vel oculto.Tecido com classifica&ccedil;&atilde;o 40 UPF para bloquear 98% dos raios UV.Certificado conforme EN ISO 20471 ap&oacute;s 50 lavagens.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/c469\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T17:09:54+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/","name":"Casaco Alta Visibilidade Portwest 3 em 1 - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg","datePublished":"2025-08-05T01:55:50+00:00","dateModified":"2026-02-06T17:09:54+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_c469.jpg","width":700,"height":700,"caption":"Casaco Alta Visibilidade Portwest 3 em 1"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/c469\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Casaco Alta Visibilidade Portwest 3 em 1"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/877419"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=877419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/877416"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=877419"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=877419"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=877419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}