{"id":883145,"date":"2025-08-23T02:56:33","date_gmt":"2025-08-23T01:56:33","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/luvas-portwest-latex-rugoso\/"},"modified":"2026-02-06T23:10:06","modified_gmt":"2026-02-06T23:10:06","slug":"a100","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/a100\/","title":{"rendered":"Grip 10 Latex Glove"},"content":{"rendered":"<div class=\"translation-block\">\n<p>Luvas Portwest L&aacute;tex Rugoso<\/p>\n<p>Uma das luvas mais populares no do mercado, a Luva Grip em latex de qualidade premium e calibre 10, apresenta uma excelente resist&ecirc;ncia &agrave; abras&atilde;o e ao desgaste, permitindo-lhe um bom desempenho em condi&ccedil;&otilde;es molhadas e secas.<br \/>Com as costas arejadas para ventila&ccedil;&atilde;o e um design ergon&oacute;mico que reduz a fadiga das m&atilde;os.<br \/>Luva de trabalho de qualidade premium.<br \/>Acabamento de l&aacute;tex Crinkle oferece excelente ader&ecirc;ncia.<br \/>O l&aacute;tex &eacute; uma borracha natural que possui um elevado n&iacute;vel de elasticidade, melhorando simultaneamente a resist&ecirc;ncia qu&iacute;mica e proporcionando uma grande ader&ecirc;ncia em condi&ccedil;&otilde;es h&uacute;midas e secas.<br \/>O poli&eacute;ster &eacute; mais resistente do que as fibras naturais e oferece uma durabilidade suficiente.<br \/>Forro resistente de calibre 10.<br \/>Forro respir&aacute;vel sem costura.<br \/>Costas abertas para respirabilidade.<br \/>Certificado CE.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Luvas Portwest L&aacute;tex Rugoso<\/p>\n<p>Uma das luvas mais populares no do mercado, a Luva Grip em latex de qualidade premium e calibre 10, apresenta uma excelente resist&ecirc;ncia &agrave; abras&atilde;o e ao desgaste, permitindo-lhe um bom desempenho em condi&ccedil;&otilde;es molhadas e secas.<br \/>Com as costas arejadas para ventila&ccedil;&atilde;o e um design ergon&oacute;mico que reduz a fadiga das m&atilde;os.<br \/>Luva de trabalho de qualidade premium.<br \/>Acabamento de l&aacute;tex Crinkle oferece excelente ader&ecirc;ncia.<br \/>O l&aacute;tex &eacute; uma borracha natural que possui um elevado n&iacute;vel de elasticidade, melhorando simultaneamente a resist&ecirc;ncia qu&iacute;mica e proporcionando uma grande ader&ecirc;ncia em condi&ccedil;&otilde;es h&uacute;midas e secas.<br \/>O poli&eacute;ster &eacute; mais resistente do que as fibras naturais e oferece uma durabilidade suficiente.<br \/>Forro resistente de calibre 10.<br \/>Forro respir&aacute;vel sem costura.<br \/>Costas abertas para respirabilidade.<br \/>Certificado CE.<\/p>\n<\/div>","protected":false},"featured_media":883142,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2749,2747],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Luvas Portwest L\u00e1tex Rugoso - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/a100\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Luvas Portwest L\u00e1tex Rugoso - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Luvas Portwest L&aacute;tex RugosoUma das luvas mais populares no do mercado, a Luva Grip em latex de qualidade premium e calibre 10, apresenta uma excelente resist&ecirc;ncia &agrave; abras&atilde;o e ao desgaste, permitindo-lhe um bom desempenho em condi&ccedil;&otilde;es molhadas e secas.Com as costas arejadas para ventila&ccedil;&atilde;o e um design ergon&oacute;mico que reduz a fadiga das m&atilde;os.Luva de trabalho de qualidade premium.Acabamento de l&aacute;tex Crinkle oferece excelente ader&ecirc;ncia.O l&aacute;tex &eacute; uma borracha natural que possui um elevado n&iacute;vel de elasticidade, melhorando simultaneamente a resist&ecirc;ncia qu&iacute;mica e proporcionando uma grande ader&ecirc;ncia em condi&ccedil;&otilde;es h&uacute;midas e secas.O poli&eacute;ster &eacute; mais resistente do que as fibras naturais e oferece uma durabilidade suficiente.Forro resistente de calibre 10.Forro respir&aacute;vel sem costura.Costas abertas para respirabilidade.Certificado CE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/a100\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T23:10:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/\",\"name\":\"Luvas Portwest L\u00e1tex Rugoso - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg\",\"datePublished\":\"2025-08-23T01:56:33+00:00\",\"dateModified\":\"2026-02-06T23:10:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg\",\"width\":700,\"height\":700,\"caption\":\"Luvas Portwest L\u00e1tex Rugoso\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Luvas Portwest L\u00e1tex Rugoso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Luvas Portwest L\u00e1tex Rugoso - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/a100\/","og_locale":"en_GB","og_type":"article","og_title":"Luvas Portwest L\u00e1tex Rugoso - NorSafe","og_description":"Luvas Portwest L&aacute;tex RugosoUma das luvas mais populares no do mercado, a Luva Grip em latex de qualidade premium e calibre 10, apresenta uma excelente resist&ecirc;ncia &agrave; abras&atilde;o e ao desgaste, permitindo-lhe um bom desempenho em condi&ccedil;&otilde;es molhadas e secas.Com as costas arejadas para ventila&ccedil;&atilde;o e um design ergon&oacute;mico que reduz a fadiga das m&atilde;os.Luva de trabalho de qualidade premium.Acabamento de l&aacute;tex Crinkle oferece excelente ader&ecirc;ncia.O l&aacute;tex &eacute; uma borracha natural que possui um elevado n&iacute;vel de elasticidade, melhorando simultaneamente a resist&ecirc;ncia qu&iacute;mica e proporcionando uma grande ader&ecirc;ncia em condi&ccedil;&otilde;es h&uacute;midas e secas.O poli&eacute;ster &eacute; mais resistente do que as fibras naturais e oferece uma durabilidade suficiente.Forro resistente de calibre 10.Forro respir&aacute;vel sem costura.Costas abertas para respirabilidade.Certificado CE.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/a100\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T23:10:06+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/","name":"Luvas Portwest L\u00e1tex Rugoso - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg","datePublished":"2025-08-23T01:56:33+00:00","dateModified":"2026-02-06T23:10:06+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_a100.jpg","width":700,"height":700,"caption":"Luvas Portwest L\u00e1tex Rugoso"},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/a100\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Luvas Portwest L\u00e1tex Rugoso"}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/883145"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=883145"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/883142"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=883145"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=883145"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=883145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}