{"id":883385,"date":"2025-09-04T02:39:17","date_gmt":"2025-09-04T01:39:17","guid":{"rendered":"https:\/\/www.norsafe.pt\/produto\/bone-5-gomos-odyssey-adulto-100alg-210gr\/"},"modified":"2026-02-06T14:16:39","modified_gmt":"2026-02-06T14:16:39","slug":"odyssey","status":"publish","type":"product","link":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/odyssey\/","title":{"rendered":"ODYSSEY Cap Adult 100% Cotton 210gr."},"content":{"rendered":"<div class=\"translation-block\">\n<p>Bon&eacute; 5 Gomos ODYSSEY Adulto 100%Alg. 210gr.<\/p>\n<p>Bon&eacute; de algod&atilde;o 5 pain&eacute;is, premium quality.<br \/>Confecionado em tecido sarja 100% algod&atilde;o para maior durabilidade, resist&ecirc;ncia e respirabilidade.<br \/>Quatro orif&iacute;cios de respira&ccedil;&atilde;o para melhor ventila&ccedil;&atilde;o e viseira curva que impede a entrada da luz solar e proporciona maior frescura.<br \/>Refor&ccedil;o interno termo-fixado que mant&eacute;m sua estrutura, e banda interior suave em contorno que favorece a absor&ccedil;&atilde;o do suor e proporciona maior conforto.<br \/>Abertura traseira semi-circular com tira de velcro para um melhor ajuste.<br \/>Painel frontal direito sem costuras que permite diferentes tipos de marca&ccedil;&atilde;o: serigrafia, vinil, transfer, bordados, cosidos.<br \/>Ideal para brindes promocionais, brindes personalizados, souvenir, merchandising e roupa desportiva.<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<div class=\"translation-block\">\n<p>Bon&eacute; 5 Gomos ODYSSEY Adulto 100%Alg. 210gr.<\/p>\n<p>Bon&eacute; de algod&atilde;o 5 pain&eacute;is, premium quality.<br \/>Confecionado em tecido sarja 100% algod&atilde;o para maior durabilidade, resist&ecirc;ncia e respirabilidade.<br \/>Quatro orif&iacute;cios de respira&ccedil;&atilde;o para melhor ventila&ccedil;&atilde;o e viseira curva que impede a entrada da luz solar e proporciona maior frescura.<br \/>Refor&ccedil;o interno termo-fixado que mant&eacute;m sua estrutura, e banda interior suave em contorno que favorece a absor&ccedil;&atilde;o do suor e proporciona maior conforto.<br \/>Abertura traseira semi-circular com tira de velcro para um melhor ajuste.<br \/>Painel frontal direito sem costuras que permite diferentes tipos de marca&ccedil;&atilde;o: serigrafia, vinil, transfer, bordados, cosidos.<br \/>Ideal para brindes promocionais, brindes personalizados, souvenir, merchandising e roupa desportiva.<\/p>\n<\/div>","protected":false},"featured_media":883382,"comment_status":"open","ping_status":"closed","template":"","meta":{"_joinchat":[]},"product_cat":[2747,2753],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr. - NorSafe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/odyssey\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr. - NorSafe\" \/>\n<meta property=\"og:description\" content=\"Bon&eacute; 5 Gomos ODYSSEY Adulto 100%Alg. 210gr.Bon&eacute; de algod&atilde;o 5 pain&eacute;is, premium quality.Confecionado em tecido sarja 100% algod&atilde;o para maior durabilidade, resist&ecirc;ncia e respirabilidade.Quatro orif&iacute;cios de respira&ccedil;&atilde;o para melhor ventila&ccedil;&atilde;o e viseira curva que impede a entrada da luz solar e proporciona maior frescura.Refor&ccedil;o interno termo-fixado que mant&eacute;m sua estrutura, e banda interior suave em contorno que favorece a absor&ccedil;&atilde;o do suor e proporciona maior conforto.Abertura traseira semi-circular com tira de velcro para um melhor ajuste.Painel frontal direito sem costuras que permite diferentes tipos de marca&ccedil;&atilde;o: serigrafia, vinil, transfer, bordados, cosidos.Ideal para brindes promocionais, brindes personalizados, souvenir, merchandising e roupa desportiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/odyssey\/\" \/>\n<meta property=\"og:site_name\" content=\"NorSafe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Norsafe.pt\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-06T14:16:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/\",\"name\":\"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr. - NorSafe\",\"isPartOf\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg\",\"datePublished\":\"2025-09-04T01:39:17+00:00\",\"dateModified\":\"2026-02-06T14:16:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#primaryimage\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg\",\"contentUrl\":\"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg\",\"width\":700,\"height\":700,\"caption\":\"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produtos\",\"item\":\"https:\/\/earsnorsafe.ftpweb.dev\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#website\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"name\":\"NorSafe\",\"description\":\"Equipamento de Prote\u00e7\u00e3o Individual (EPI)\",\"publisher\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#organization\",\"name\":\"NORSAFE - We Protect\",\"url\":\"https:\/\/earsnorsafe.ftpweb.dev\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"contentUrl\":\"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png\",\"width\":908,\"height\":603,\"caption\":\"NORSAFE - We Protect\"},\"image\":{\"@id\":\"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/Norsafe.pt\/\",\"https:\/\/www.instagram.com\/norsafe.lda\",\"https:\/\/pt.linkedin.com\/company\/norsafe-lda\",\"https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr. - NorSafe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/odyssey\/","og_locale":"en_GB","og_type":"article","og_title":"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr. - NorSafe","og_description":"Bon&eacute; 5 Gomos ODYSSEY Adulto 100%Alg. 210gr.Bon&eacute; de algod&atilde;o 5 pain&eacute;is, premium quality.Confecionado em tecido sarja 100% algod&atilde;o para maior durabilidade, resist&ecirc;ncia e respirabilidade.Quatro orif&iacute;cios de respira&ccedil;&atilde;o para melhor ventila&ccedil;&atilde;o e viseira curva que impede a entrada da luz solar e proporciona maior frescura.Refor&ccedil;o interno termo-fixado que mant&eacute;m sua estrutura, e banda interior suave em contorno que favorece a absor&ccedil;&atilde;o do suor e proporciona maior conforto.Abertura traseira semi-circular com tira de velcro para um melhor ajuste.Painel frontal direito sem costuras que permite diferentes tipos de marca&ccedil;&atilde;o: serigrafia, vinil, transfer, bordados, cosidos.Ideal para brindes promocionais, brindes personalizados, souvenir, merchandising e roupa desportiva.","og_url":"https:\/\/earsnorsafe.ftpweb.dev\/en\/product\/odyssey\/","og_site_name":"NorSafe","article_publisher":"https:\/\/www.facebook.com\/Norsafe.pt\/","article_modified_time":"2026-02-06T14:16:39+00:00","og_image":[{"width":700,"height":700,"url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/","url":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/","name":"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr. - NorSafe","isPartOf":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website"},"primaryImageOfPage":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#primaryimage"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#primaryimage"},"thumbnailUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg","datePublished":"2025-09-04T01:39:17+00:00","dateModified":"2026-02-06T14:16:39+00:00","breadcrumb":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#primaryimage","url":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg","contentUrl":"https:\/\/earsnorsafe.ftpweb.dev\/wp-content\/uploads\/nsf_odyssey.jpg","width":700,"height":700,"caption":"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr."},{"@type":"BreadcrumbList","@id":"https:\/\/earsnorsafe.ftpweb.dev\/produto\/odyssey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/earsnorsafe.ftpweb.dev\/"},{"@type":"ListItem","position":2,"name":"Produtos","item":"https:\/\/earsnorsafe.ftpweb.dev\/shop\/"},{"@type":"ListItem","position":3,"name":"Bon\u00e9 5 Gomos ODYSSEY Adulto 100%Alg. 210gr."}]},{"@type":"WebSite","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#website","url":"https:\/\/earsnorsafe.ftpweb.dev\/","name":"NorSafe","description":"Equipamento de Prote\u00e7\u00e3o Individual (EPI)","publisher":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/earsnorsafe.ftpweb.dev\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#organization","name":"NORSAFE - We Protect","url":"https:\/\/earsnorsafe.ftpweb.dev\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/","url":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","contentUrl":"https:\/\/www.norsafe.pt\/wp-content\/uploads\/2021\/03\/Logo-NorSafe-Cor-Original.png","width":908,"height":603,"caption":"NORSAFE - We Protect"},"image":{"@id":"https:\/\/earsnorsafe.ftpweb.dev\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Norsafe.pt\/","https:\/\/www.instagram.com\/norsafe.lda","https:\/\/pt.linkedin.com\/company\/norsafe-lda","https:\/\/www.youtube.com\/channel\/UCC93zqoQaAs2ugjBq9SeINA"]}]}},"_links":{"self":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product\/883385"}],"collection":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/comments?post=883385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media\/883382"}],"wp:attachment":[{"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/media?parent=883385"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_cat?post=883385"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/earsnorsafe.ftpweb.dev\/en\/wp-json\/wp\/v2\/product_tag?post=883385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}